{"id":3609,"date":"2026-03-19T17:36:44","date_gmt":"2026-03-19T20:36:44","guid":{"rendered":"https:\/\/portal.pi.gov.br\/sasc\/?p=3609"},"modified":"2026-04-27T10:08:07","modified_gmt":"2026-04-27T13:08:07","slug":"sasc-abre-inscricoes-para-o-comite-estadual-de-prevencao-e-combate-a-tortura","status":"publish","type":"post","link":"https:\/\/portal.pi.gov.br\/sasc\/2026\/03\/19\/sasc-abre-inscricoes-para-o-comite-estadual-de-prevencao-e-combate-a-tortura\/","title":{"rendered":"Sasc abre inscri\u00e7\u00f5es para o Comit\u00ea Estadual de Preven\u00e7\u00e3o e Combate \u00e0 Tortura"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es ser\u00e3o realizadas de 26 de mar\u00e7o \u00e0 26 de abril de 2026.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A Secretaria do Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome (Sasc), por meio da Superintend\u00eancia de Direitos Humanos (SUDH), divulgou o processo de composi\u00e7\u00e3o do Comit\u00ea Estadual de Preven\u00e7\u00e3o e Combate \u00e0 Tortura (CEPCT\/PI), institu\u00eddo pela Lei Estadual n\u00ba 8.809\/2025. O Comit\u00ea integra o Sistema Estadual de Preven\u00e7\u00e3o e Combate \u00e0 Tortura, com o objetivo de prevenir e combater pr\u00e1ticas de tortura e outros tratamentos cru\u00e9is, desumanos ou degradantes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>O comit\u00ea ser\u00e1 formado por 11 membros, sendo 05 representantes do Estado, que dever\u00e3o integrar a Secretaria do Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome (Sasc), Secretaria de Estado da Sa\u00fade (Sesapi), Secretaria de Estado para Inclus\u00e3o da Pessoa com Defici\u00eancia (Seid), Secretaria de Estado das Mulheres (Sempi) e Secretaria de Estado da Educa\u00e7\u00e3o (Seduc).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.pi.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.05.11-e1773951377345.jpeg\" alt=\"\" class=\"wp-image-124583\" \/><\/figure>\n\n\n\n<p>Foto : Ascom Sasc<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>As outras seis vagas restantes ser\u00e3o destinadas para representantes da sociedade civil, que dever\u00e3o ser escolhidos por meio de processo eleitoral entre as entidades com atua\u00e7\u00e3o comprovada na defesa dos direitos humanos e na preven\u00e7\u00e3o e combate \u00e0 tortura.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es estar\u00e3o abertas de 26 de mar\u00e7o \u00e0 26 de abril de 2026, podendo ser prorrogadas por at\u00e9 15 dias. A elei\u00e7\u00e3o ser\u00e1 conduzida por uma Comiss\u00e3o Eleitoral da Sasc, garantindo publicidade, transpar\u00eancia e participa\u00e7\u00e3o democr\u00e1tica. A lista de entidades habilitadas ser\u00e1 publicada no Di\u00e1rio Oficial e no site da Sasc.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Confira o <a href=\"https:\/\/forms.gle\/soVKtmN8PXdK24Zr7\" data-type=\"URL\" data-id=\"https:\/\/forms.gle\/soVKtmN8PXdK24Zr7\">formul\u00e1rio<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As inscri\u00e7\u00f5es ser\u00e3o realizadas de 26 de mar\u00e7o \u00e0 26 de abril de 2026. A Secretaria do Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome (Sasc), por meio da [&hellip;]<\/p>\n","protected":false},"author":1807,"featured_media":3610,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[30],"tags":[],"featured_image_urls":{"full":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55.jpeg",1600,1066,false],"thumbnail":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-150x150.jpeg",150,150,true],"medium":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-300x200.jpeg",300,200,true],"medium_large":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-768x512.jpeg",768,512,true],"large":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-1024x682.jpeg",887,591,true],"sgg-420":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-420x280.jpeg",420,280,true],"sgg-540":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-540x360.jpeg",540,360,true],"sgg-780":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-780x520.jpeg",780,520,true],"1536x1536":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-1536x1023.jpeg",1536,1023,true],"2048x2048":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55.jpeg",1600,1066,false],"homepage-slider":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-1270x500.jpeg",1270,500,true],"homepage-slider-small":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-947x500.jpeg",947,500,true],"page-top":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-947x631.jpeg",947,631,true],"page-small":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-624x416.jpeg",624,416,true],"loop-main":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-365x240.jpeg",365,240,true],"thumb-gallery-widget":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-84x56.jpeg",84,56,true]},"post_excerpt_stackable":"<p>As inscri\u00e7\u00f5es ser\u00e3o realizadas de 26 de mar\u00e7o \u00e0 26 de abril de 2026. A Secretaria do Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome (Sasc), por meio da Superintend\u00eancia de Direitos Humanos (SUDH), divulgou o processo de composi\u00e7\u00e3o do Comit\u00ea Estadual de Preven\u00e7\u00e3o e Combate \u00e0 Tortura (CEPCT\/PI), institu\u00eddo pela Lei Estadual n\u00ba 8.809\/2025. O Comit\u00ea integra o Sistema Estadual de Preven\u00e7\u00e3o e Combate \u00e0 Tortura, com o objetivo de prevenir e combater pr\u00e1ticas de tortura e outros tratamentos cru\u00e9is, desumanos ou degradantes. O comit\u00ea ser\u00e1 formado por 11 membros, sendo 05 representantes do Estado, que dever\u00e3o integrar&hellip;<\/p>\n","category_list":"<a href=\"https:\/\/portal.pi.gov.br\/sasc\/category\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","author_info":{"name":"jeansilva","url":"https:\/\/portal.pi.gov.br\/sasc\/author\/jeansilva\/"},"comments_num":"0 coment\u00e1rio","featured_image_urls_v2":{"full":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55.jpeg",1600,1066,false],"thumbnail":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-150x150.jpeg",150,150,true],"medium":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-300x200.jpeg",300,200,true],"medium_large":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-768x512.jpeg",768,512,true],"large":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-1024x682.jpeg",887,591,true],"sgg-420":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-420x280.jpeg",420,280,true],"sgg-540":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-540x360.jpeg",540,360,true],"sgg-780":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-780x520.jpeg",780,520,true],"1536x1536":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-1536x1023.jpeg",1536,1023,true],"2048x2048":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55.jpeg",1600,1066,false],"homepage-slider":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-1270x500.jpeg",1270,500,true],"homepage-slider-small":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-947x500.jpeg",947,500,true],"page-top":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-947x631.jpeg",947,631,true],"page-small":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-624x416.jpeg",624,416,true],"loop-main":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-365x240.jpeg",365,240,true],"thumb-gallery-widget":["https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55-84x56.jpeg",84,56,true]},"post_excerpt_stackable_v2":"<p>As inscri\u00e7\u00f5es ser\u00e3o realizadas de 26 de mar\u00e7o \u00e0 26 de abril de 2026. A Secretaria do Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome (Sasc), por meio da Superintend\u00eancia de Direitos Humanos (SUDH), divulgou o processo de composi\u00e7\u00e3o do Comit\u00ea Estadual de Preven\u00e7\u00e3o e Combate \u00e0 Tortura (CEPCT\/PI), institu\u00eddo pela Lei Estadual n\u00ba 8.809\/2025. O Comit\u00ea integra o Sistema Estadual de Preven\u00e7\u00e3o e Combate \u00e0 Tortura, com o objetivo de prevenir e combater pr\u00e1ticas de tortura e outros tratamentos cru\u00e9is, desumanos ou degradantes. O comit\u00ea ser\u00e1 formado por 11 membros, sendo 05 representantes do Estado, que dever\u00e3o integrar&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/portal.pi.gov.br\/sasc\/category\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","author_info_v2":{"name":"jeansilva","url":"https:\/\/portal.pi.gov.br\/sasc\/author\/jeansilva\/"},"comments_num_v2":"0 coment\u00e1rio","jetpack_featured_media_url":"https:\/\/portal.pi.gov.br\/sasc\/wp-content\/uploads\/sites\/104\/2026\/03\/WhatsApp-Image-2026-03-19-at-17.34.55.jpeg","_links":{"self":[{"href":"https:\/\/portal.pi.gov.br\/sasc\/wp-json\/wp\/v2\/posts\/3609"}],"collection":[{"href":"https:\/\/portal.pi.gov.br\/sasc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portal.pi.gov.br\/sasc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portal.pi.gov.br\/sasc\/wp-json\/wp\/v2\/users\/1807"}],"replies":[{"embeddable":true,"href":"https:\/\/portal.pi.gov.br\/sasc\/wp-json\/wp\/v2\/comments?post=3609"}],"version-history":[{"count":5,"href":"https:\/\/portal.pi.gov.br\/sasc\/wp-json\/wp\/v2\/posts\/3609\/revisions"}],"predecessor-version":[{"id":3724,"href":"https:\/\/portal.pi.gov.br\/sasc\/wp-json\/wp\/v2\/posts\/3609\/revisions\/3724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portal.pi.gov.br\/sasc\/wp-json\/wp\/v2\/media\/3610"}],"wp:attachment":[{"href":"https:\/\/portal.pi.gov.br\/sasc\/wp-json\/wp\/v2\/media?parent=3609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portal.pi.gov.br\/sasc\/wp-json\/wp\/v2\/categories?post=3609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portal.pi.gov.br\/sasc\/wp-json\/wp\/v2\/tags?post=3609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}